{"id":814,"date":"2020-09-21T11:33:30","date_gmt":"2020-09-21T09:33:30","guid":{"rendered":"https:\/\/capovilla.org\/?p=814"},"modified":"2020-11-17T17:54:46","modified_gmt":"2020-11-17T16:54:46","slug":"une-initiative-du-chs","status":"publish","type":"post","link":"https:\/\/capovilla.org\/index.php\/2020\/09\/21\/une-initiative-du-chs\/","title":{"rendered":"Une initiative du CHS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Une nouvelle initiative vid\u00e9o du CHS (Centre d&rsquo;Histoire Sociale), r\u00e9alis\u00e9e par Jeanne Menjoulet : le 1er volet d&rsquo;Une histoire du salariat.<br>\u00c0 d\u00e9couvrir sur Youtube :<br><a rel=\"noreferrer noopener\" href=\"https:\/\/www.youtube.com\/watch?v=AnfT3rSGC9I\" target=\"_blank\">Une histoire du salariat &#8211; 19\u00e8me si\u00e8cle &#8211; un travail sans contrat de travail<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une nouvelle initiative vid\u00e9o du CHS (Centre d&rsquo;Histoire Sociale), r\u00e9alis\u00e9e par Jeanne Menjoulet : le 1er volet d&rsquo;Une histoire du salariat.\u00c0 d\u00e9couvrir sur Youtube :Une histoire du salariat &#8211; 19\u00e8me si\u00e8cle &#8211; un travail&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":816,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[33],"tags":[],"class_list":["post-814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article-partenaire"],"views":1355,"_links":{"self":[{"href":"https:\/\/capovilla.org\/index.php\/wp-json\/wp\/v2\/posts\/814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/capovilla.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/capovilla.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/capovilla.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/capovilla.org\/index.php\/wp-json\/wp\/v2\/comments?post=814"}],"version-history":[{"count":1,"href":"https:\/\/capovilla.org\/index.php\/wp-json\/wp\/v2\/posts\/814\/revisions"}],"predecessor-version":[{"id":815,"href":"https:\/\/capovilla.org\/index.php\/wp-json\/wp\/v2\/posts\/814\/revisions\/815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/capovilla.org\/index.php\/wp-json\/wp\/v2\/media\/816"}],"wp:attachment":[{"href":"https:\/\/capovilla.org\/index.php\/wp-json\/wp\/v2\/media?parent=814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/capovilla.org\/index.php\/wp-json\/wp\/v2\/categories?post=814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/capovilla.org\/index.php\/wp-json\/wp\/v2\/tags?post=814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}